{"id":3323,"count":17,"description":"","link":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/","name":"Interdisciplinary Conference on Psychedelic Research (ICPR)","slug":"interdisciplinary-conference-on-psychedelic-research-icpr","taxonomy":"video-series","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin  - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Interdisciplinary Conference on Psychedelic Research (ICPR) Archives - Drugreporter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interdisciplinary Conference on Psychedelic Research (ICPR) Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/\" \/>\n<meta property=\"og:site_name\" content=\"Drugreporter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/video-series\\\/interdisciplinary-conference-on-psychedelic-research-icpr\\\/\",\"url\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/video-series\\\/interdisciplinary-conference-on-psychedelic-research-icpr\\\/\",\"name\":\"Interdisciplinary Conference on Psychedelic Research (ICPR) Archives - Drugreporter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/video-series\\\/interdisciplinary-conference-on-psychedelic-research-icpr\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/video-series\\\/interdisciplinary-conference-on-psychedelic-research-icpr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interdisciplinary Conference on Psychedelic Research (ICPR)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/\",\"name\":\"Drugreporter\",\"description\":\"News and Films from the Frontline of the War on Drugs\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drogriporter.hu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Interdisciplinary Conference on Psychedelic Research (ICPR) Archives - Drugreporter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/","og_locale":"en_US","og_type":"article","og_title":"Interdisciplinary Conference on Psychedelic Research (ICPR) Archives","og_url":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/","og_site_name":"Drugreporter","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/","url":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/","name":"Interdisciplinary Conference on Psychedelic Research (ICPR) Archives - Drugreporter","isPartOf":{"@id":"https:\/\/drogriporter.hu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/drogriporter.hu\/en\/video-series\/interdisciplinary-conference-on-psychedelic-research-icpr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/drogriporter.hu\/en\/"},{"@type":"ListItem","position":2,"name":"Interdisciplinary Conference on Psychedelic Research (ICPR)"}]},{"@type":"WebSite","@id":"https:\/\/drogriporter.hu\/en\/#website","url":"https:\/\/drogriporter.hu\/en\/","name":"Drugreporter","description":"News and Films from the Frontline of the War on Drugs","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drogriporter.hu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/drogriporter.hu\/en\/wp-json\/wp\/v2\/video-series\/3323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drogriporter.hu\/en\/wp-json\/wp\/v2\/video-series"}],"about":[{"href":"https:\/\/drogriporter.hu\/en\/wp-json\/wp\/v2\/taxonomies\/video-series"}],"wp:post_type":[{"href":"https:\/\/drogriporter.hu\/en\/wp-json\/wp\/v2\/posts?video-series=3323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}